{"id":11221,"date":"2024-08-15T08:38:45","date_gmt":"2024-08-15T01:38:45","guid":{"rendered":"https:\/\/entechsi.com\/?p=11221"},"modified":"2024-08-15T10:15:11","modified_gmt":"2024-08-15T03:15:11","slug":"%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%ad%e0%b8%b2%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%82%e0%b8%99%e0%b8%b2%e0%b8%94%e0%b8%a2%e0%b9%88%e0%b8%ad%e0%b8%a1-microclim","status":"publish","type":"post","link":"https:\/\/entechsi.com\/en\/%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%ad%e0%b8%b2%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%82%e0%b8%99%e0%b8%b2%e0%b8%94%e0%b8%a2%e0%b9%88%e0%b8%ad%e0%b8%a1-microclim\/","title":{"rendered":"\u0e2a\u0e20\u0e32\u0e1e\u0e20\u0e39\u0e21\u0e34\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e02\u0e19\u0e32\u0e14\u0e22\u0e48\u0e2d\u0e21 (Microclimate) \u0e01\u0e31\u0e1a\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"11221\" class=\"elementor elementor-11221\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-91a1ea5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"91a1ea5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-00a45db\" data-id=\"00a45db\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cec71fc elementor-widget elementor-widget-image\" data-id=\"cec71fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1200\" height=\"337\" src=\"https:\/\/entechsi.com\/wp-content\/uploads\/2024\/08\/\u0e2a\u0e20\u0e32\u0e1e\u0e20\u0e39\u0e21\u0e34\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e02\u0e19\u0e32\u0e14\u0e22\u0e48\u0e2d\u0e21-Microclimate-\u0e01\u0e31\u0e1a\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22-01.jpg\" class=\"attachment-full size-full wp-image-11224\" alt=\"\u0e2a\u0e20\u0e32\u0e1e\u0e20\u0e39\u0e21\u0e34\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e02\u0e19\u0e32\u0e14\u0e22\u0e48\u0e2d\u0e21 (microclimate) \u0e01\u0e31\u0e1a\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 01\" srcset=\"https:\/\/entechsi.com\/wp-content\/uploads\/2024\/08\/\u0e2a\u0e20\u0e32\u0e1e\u0e20\u0e39\u0e21\u0e34\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e02\u0e19\u0e32\u0e14\u0e22\u0e48\u0e2d\u0e21-Microclimate-\u0e01\u0e31\u0e1a\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22-01.jpg 1200w, https:\/\/entechsi.com\/wp-content\/uploads\/2024\/08\/\u0e2a\u0e20\u0e32\u0e1e\u0e20\u0e39\u0e21\u0e34\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e02\u0e19\u0e32\u0e14\u0e22\u0e48\u0e2d\u0e21-Microclimate-\u0e01\u0e31\u0e1a\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22-01-300x84.jpg 300w, https:\/\/entechsi.com\/wp-content\/uploads\/2024\/08\/\u0e2a\u0e20\u0e32\u0e1e\u0e20\u0e39\u0e21\u0e34\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e02\u0e19\u0e32\u0e14\u0e22\u0e48\u0e2d\u0e21-Microclimate-\u0e01\u0e31\u0e1a\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22-01-1024x288.jpg 1024w, https:\/\/entechsi.com\/wp-content\/uploads\/2024\/08\/\u0e2a\u0e20\u0e32\u0e1e\u0e20\u0e39\u0e21\u0e34\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e02\u0e19\u0e32\u0e14\u0e22\u0e48\u0e2d\u0e21-Microclimate-\u0e01\u0e31\u0e1a\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22-01-768x216.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bfdb4af elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bfdb4af\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-9af2770\" data-id=\"9af2770\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-faa099a\" data-id=\"faa099a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-851ee37 elementor-widget elementor-widget-text-editor\" data-id=\"851ee37\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\u0e2a\u0e20\u0e32\u0e1e\u0e20\u0e39\u0e21\u0e34\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e02\u0e19\u0e32\u0e14\u0e22\u0e48\u0e2d\u0e21 (Microclimate) \u0e2a\u0e37\u0e48\u0e2d\u0e16\u0e36\u0e07\u0e2a\u0e20\u0e32\u0e1e\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e02\u0e19\u0e32\u0e14\u0e22\u0e48\u0e2d\u0e21\u0e20\u0e32\u0e22\u0e43\u0e19\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e17\u0e35\u0e48\u0e01\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e34\u0e14\u0e42\u0e25\u0e48\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e17\u0e35\u0e48\u0e42\u0e25\u0e48\u0e07  \u0e23\u0e27\u0e21\u0e08\u0e19\u0e16\u0e36\u0e07\u0e2a\u0e20\u0e32\u0e1e\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e02\u0e2d\u0e07\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22\u0e1b\u0e31\u0e08\u0e08\u0e31\u0e22\u0e17\u0e32\u0e07\u0e01\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e2b\u0e25\u0e32\u0e22\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e17\u0e35\u0e48\u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e15\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e17\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e02\u0e2d\u0e07\u0e21\u0e19\u0e38\u0e29\u0e22\u0e4c \u0e40\u0e0a\u0e48\u0e19 \u0e2d\u0e38\u0e13\u0e2b\u0e20\u0e39\u0e21\u0e34 \u0e04\u0e27\u0e32\u0e21\u0e0a\u0e37\u0e49\u0e19\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e17\u0e18\u0e4c \u0e2d\u0e38\u0e13\u0e2b\u0e20\u0e39\u0e21\u0e34\u0e40\u0e09\u0e25\u0e35\u0e48\u0e22\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1c\u0e48\u0e23\u0e31\u0e07\u0e2a\u0e35\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e25\u0e21 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19 \u0e40\u0e14\u0e34\u0e21\u0e17\u0e35\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e2a\u0e20\u0e32\u0e1e\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e17\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e21\u0e38\u0e48\u0e07\u0e40\u0e19\u0e49\u0e19\u0e44\u0e1b\u0e17\u0e35\u0e48\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e02\u0e2d\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e14\u0e31\u0e07\u0e19\u0e31\u0e49\u0e19 \u0e2a\u0e20\u0e32\u0e1e\u0e20\u0e39\u0e21\u0e34\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e02\u0e19\u0e32\u0e14\u0e22\u0e48\u0e2d\u0e21 (Microclimate) \u0e08\u0e36\u0e07\u0e16\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e43\u0e19\u0e1b\u0e31\u0e08\u0e08\u0e31\u0e22\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07\u0e17\u0e32\u0e07\u0e01\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e17\u0e35\u0e48\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e2b\u0e25\u0e32\u0e22\u0e09\u0e1a\u0e31\u0e1a\u0e02\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49 \u0e0b\u0e36\u0e48\u0e07\u0e43\u0e19\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e22\u0e2d\u0e21\u0e23\u0e31\u0e1a\u0e01\u0e31\u0e19\u0e14\u0e35\u0e27\u0e48\u0e32 \u0e2a\u0e20\u0e32\u0e1e\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e0a\u0e37\u0e49\u0e19\u0e43\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e15\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e2a\u0e20\u0e32\u0e27\u0e30\u0e1b\u0e01\u0e15\u0e34 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e15\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e02\u0e2d\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e43\u0e19\u0e2a\u0e20\u0e32\u0e27\u0e30\u0e17\u0e35\u0e48\u0e23\u0e38\u0e19\u0e41\u0e23\u0e07\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-50b6c86\" data-id=\"50b6c86\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1c3dc98 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1c3dc98\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-d8ef168\" data-id=\"d8ef168\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-b7313d1\" data-id=\"b7313d1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6bc3d63 elementor-widget elementor-widget-image\" data-id=\"6bc3d63\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"627\" height=\"887\" src=\"https:\/\/entechsi.com\/wp-content\/uploads\/2024\/08\/\u0e2a\u0e20\u0e32\u0e1e\u0e20\u0e39\u0e21\u0e34\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e02\u0e19\u0e32\u0e14\u0e22\u0e48\u0e2d\u0e21-Microclimate-\u0e01\u0e31\u0e1a\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22-02.jpg\" class=\"attachment-full size-full wp-image-11226\" alt=\"\u0e2a\u0e20\u0e32\u0e1e\u0e20\u0e39\u0e21\u0e34\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e02\u0e19\u0e32\u0e14\u0e22\u0e48\u0e2d\u0e21 (microclimate) \u0e01\u0e31\u0e1a\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 02\" srcset=\"https:\/\/entechsi.com\/wp-content\/uploads\/2024\/08\/\u0e2a\u0e20\u0e32\u0e1e\u0e20\u0e39\u0e21\u0e34\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e02\u0e19\u0e32\u0e14\u0e22\u0e48\u0e2d\u0e21-Microclimate-\u0e01\u0e31\u0e1a\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22-02.jpg 627w, https:\/\/entechsi.com\/wp-content\/uploads\/2024\/08\/\u0e2a\u0e20\u0e32\u0e1e\u0e20\u0e39\u0e21\u0e34\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e02\u0e19\u0e32\u0e14\u0e22\u0e48\u0e2d\u0e21-Microclimate-\u0e01\u0e31\u0e1a\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22-02-212x300.jpg 212w\" sizes=\"(max-width: 627px) 100vw, 627px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-3ccfc42\" data-id=\"3ccfc42\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b566f89 elementor-widget elementor-widget-text-editor\" data-id=\"b566f89\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\u0e15\u0e32\u0e21\u0e2b\u0e25\u0e31\u0e01\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e41\u0e25\u0e49\u0e27 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e2a\u0e20\u0e32\u0e1e\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e17\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e21\u0e35\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22\u0e2b\u0e25\u0e31\u0e01\u0e04\u0e37\u0e2d \u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e1a\u0e32\u0e22\u0e17\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e14\u0e35\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14 \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e15\u0e48\u0e2d\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e19\u0e48\u0e32\u0e2d\u0e22\u0e39\u0e48\u0e02\u0e2d\u0e07\u0e2a\u0e20\u0e32\u0e1e\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21 \u0e43\u0e19\u0e2a\u0e20\u0e32\u0e1e\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e23\u0e38\u0e19\u0e41\u0e23\u0e07 (\u0e17\u0e31\u0e49\u0e07\u0e23\u0e49\u0e2d\u0e19\u0e08\u0e31\u0e14\u0e41\u0e25\u0e30\u0e40\u0e22\u0e47\u0e19\u0e08\u0e31\u0e14) \u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22\u0e2b\u0e25\u0e31\u0e01\u0e04\u0e37\u0e2d \u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e1c\u0e39\u0e49\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e08\u0e32\u0e01\u0e2a\u0e20\u0e32\u0e27\u0e30\u0e17\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e31\u0e19\u0e15\u0e23\u0e32\u0e22 \u0e0b\u0e36\u0e48\u0e07\u0e2d\u0e32\u0e08\u0e01\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e23\u0e42\u0e23\u0e04\u0e25\u0e21\u0e23\u0e49\u0e2d\u0e19 (heat stroke) (\u0e43\u0e19\u0e2a\u0e20\u0e32\u0e1e\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e17\u0e35\u0e48\u0e23\u0e49\u0e2d\u0e19\u0e08\u0e31\u0e14) \u0e2d\u0e32\u0e01\u0e32\u0e23\u0e2a\u0e20\u0e32\u0e27\u0e30\u0e15\u0e31\u0e27\u0e40\u0e22\u0e47\u0e19 (\u0e43\u0e19\u0e2a\u0e20\u0e32\u0e1e\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e41\u0e1a\u0e1a\u0e40\u0e22\u0e47\u0e19) \u0e14\u0e31\u0e07\u0e19\u0e31\u0e49\u0e19\u0e43\u0e19\u0e01\u0e23\u0e13\u0e35\u0e17\u0e35\u0e48\u0e01\u0e25\u0e48\u0e32\u0e27\u0e21\u0e32\u0e02\u0e49\u0e32\u0e07\u0e15\u0e49\u0e19 \u0e01\u0e32\u0e23\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e2a\u0e20\u0e32\u0e1e\u0e20\u0e39\u0e21\u0e34\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e02\u0e19\u0e32\u0e14\u0e22\u0e48\u0e2d\u0e21 (Microclimate) \u0e08\u0e36\u0e07\u0e21\u0e38\u0e48\u0e07\u0e40\u0e19\u0e49\u0e19\u0e44\u0e1b\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07 \u0e42\u0e14\u0e22\u0e40\u0e1b\u0e23\u0e35\u0e22\u0e1a\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e2a\u0e20\u0e32\u0e1e\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e01\u0e31\u0e1a\u0e2a\u0e20\u0e32\u0e1e\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e17\u0e35\u0e48\u0e2d\u0e32\u0e08\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e31\u0e19\u0e15\u0e23\u0e32\u0e22  \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-57d88a0 elementor-widget elementor-widget-text-editor\" data-id=\"57d88a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e17\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e02\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e08\u0e30\u0e43\u0e0a\u0e49\u0e01\u0e32\u0e23\u0e04\u0e33\u0e19\u0e27\u0e13\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e15\u0e32\u0e21\u0e1b\u0e31\u0e08\u0e08\u0e31\u0e22\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e40\u0e23\u0e35\u0e22\u0e01\u0e27\u0e48\u0e32\u0e14\u0e31\u0e0a\u0e19\u0e35\u0e2a\u0e20\u0e32\u0e1e\u0e20\u0e39\u0e21\u0e34\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e02\u0e19\u0e32\u0e14\u0e22\u0e48\u0e2d\u0e21 (microclimatic indexes) \u0e21\u0e35\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e38\u0e1b\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e20\u0e32\u0e1e\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22\u0e15\u0e31\u0e27\u0e41\u0e1b\u0e23\u0e2b\u0e25\u0e32\u0e22\u0e2d\u0e22\u0e48\u0e32\u0e07 (\u0e1b\u0e23\u0e34\u0e21\u0e32\u0e13\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 &#8211; \u0e04\u0e27\u0e32\u0e21\u0e0a\u0e37\u0e49\u0e19 \u0e41\u0e25\u0e30\u0e15\u0e31\u0e27\u0e41\u0e1b\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e40\u0e0a\u0e48\u0e19 \u0e2d\u0e31\u0e15\u0e23\u0e32\u0e01\u0e32\u0e23\u0e40\u0e1c\u0e32\u0e1c\u0e25\u0e32\u0e0d\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2a\u0e27\u0e21\u0e43\u0e2a\u0e48\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e21\u0e23\u0e23\u0e16\u0e19\u0e30\u0e17\u0e32\u0e07\u0e01\u0e25) \u0e0b\u0e36\u0e48\u0e07\u0e21\u0e35\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e15\u0e48\u0e2d\u0e01\u0e31\u0e19 \u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e04\u0e33\u0e19\u0e27\u0e13\u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e19\u0e33\u0e44\u0e1b\u0e40\u0e1b\u0e23\u0e35\u0e22\u0e1a\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e44\u0e14\u0e49 \u0e04\u0e48\u0e32\u0e14\u0e31\u0e0a\u0e19\u0e35\u0e17\u0e35\u0e48\u0e41\u0e15\u0e01\u0e15\u0e48\u0e32\u0e07\u0e01\u0e31\u0e19\u0e08\u0e30\u0e19\u0e33\u0e44\u0e1b\u0e43\u0e0a\u0e49\u0e01\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e02\u0e2d\u0e07\u0e2a\u0e20\u0e32\u0e1e\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e17\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e41\u0e15\u0e01\u0e15\u0e48\u0e32\u0e07\u0e01\u0e31\u0e19\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-134d69a\" data-id=\"134d69a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d63823b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d63823b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-516dd3b\" data-id=\"516dd3b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-b54a046\" data-id=\"b54a046\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-95794e8 elementor-widget elementor-widget-text-editor\" data-id=\"95794e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e44\u0e21\u0e48\u0e01\u0e35\u0e48\u0e1b\u0e35\u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32\u0e19\u0e35\u0e49 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e2a\u0e20\u0e32\u0e1e\u0e20\u0e39\u0e21\u0e34\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e02\u0e19\u0e32\u0e14\u0e22\u0e48\u0e2d\u0e21 \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e34\u0e48\u0e07\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e1a\u0e32\u0e22\u0e17\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e16\u0e39\u0e01\u0e19\u0e33\u0e21\u0e32\u0e43\u0e0a\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e43\u0e19\u0e2d\u0e07\u0e04\u0e4c\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e14\u0e49\u0e32\u0e19\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e21\u0e35\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e43\u0e0a\u0e49\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e07\u0e32\u0e19\u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21 \u0e41\u0e25\u0e30\u0e22\u0e31\u0e07\u0e04\u0e07\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e1a\u0e32\u0e22\u0e17\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e0a\u0e37\u0e49\u0e19\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e17\u0e35\u0e48\u0e17\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e44\u0e27\u0e49 \u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e32\u0e23\u0e32\u0e21\u0e34\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e2a\u0e20\u0e32\u0e1e\u0e20\u0e39\u0e21\u0e34\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e02\u0e19\u0e32\u0e14\u0e22\u0e48\u0e2d\u0e21 \u0e08\u0e30\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e19\u0e01\u0e32\u0e23\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e43\u0e2b\u0e49\u0e17\u0e33\u0e07\u0e32\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e \u0e25\u0e14\u0e01\u0e32\u0e23\u0e2a\u0e34\u0e49\u0e19\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e07\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u0e04\u0e27\u0e1a\u0e04\u0e39\u0e48\u0e44\u0e1b\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e2a\u0e1a\u0e32\u0e22\u0e43\u0e19\u0e01\u0e32\u0e23\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-325e02c\" data-id=\"325e02c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e0dcce0 elementor-widget elementor-widget-image\" data-id=\"e0dcce0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"717\" height=\"456\" src=\"https:\/\/entechsi.com\/wp-content\/uploads\/2024\/08\/\u0e2a\u0e20\u0e32\u0e1e\u0e20\u0e39\u0e21\u0e34\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e02\u0e19\u0e32\u0e14\u0e22\u0e48\u0e2d\u0e21-Microclimate-\u0e01\u0e31\u0e1a\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22-03.jpg\" class=\"attachment-full size-full wp-image-11228\" alt=\"\u0e2a\u0e20\u0e32\u0e1e\u0e20\u0e39\u0e21\u0e34\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e02\u0e19\u0e32\u0e14\u0e22\u0e48\u0e2d\u0e21 (microclimate) \u0e01\u0e31\u0e1a\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 03\" srcset=\"https:\/\/entechsi.com\/wp-content\/uploads\/2024\/08\/\u0e2a\u0e20\u0e32\u0e1e\u0e20\u0e39\u0e21\u0e34\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e02\u0e19\u0e32\u0e14\u0e22\u0e48\u0e2d\u0e21-Microclimate-\u0e01\u0e31\u0e1a\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22-03.jpg 717w, https:\/\/entechsi.com\/wp-content\/uploads\/2024\/08\/\u0e2a\u0e20\u0e32\u0e1e\u0e20\u0e39\u0e21\u0e34\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e02\u0e19\u0e32\u0e14\u0e22\u0e48\u0e2d\u0e21-Microclimate-\u0e01\u0e31\u0e1a\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22-03-300x191.jpg 300w\" sizes=\"(max-width: 717px) 100vw, 717px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-f604895\" data-id=\"f604895\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4b28d2c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4b28d2c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-19198bd\" data-id=\"19198bd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-b6fbc5c\" data-id=\"b6fbc5c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0cd40f4 elementor-widget elementor-widget-text-editor\" data-id=\"0cd40f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1a\u0e23\u0e23\u0e40\u0e17\u0e32\u0e2a\u0e20\u0e32\u0e1e\u0e20\u0e39\u0e21\u0e34\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e20\u0e32\u0e1e\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e17\u0e35\u0e48\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19 \u0e41\u0e25\u0e30\u0e19\u0e48\u0e32\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e21\u0e32\u0e01\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e2a\u0e20\u0e32\u0e1e\u0e20\u0e39\u0e21\u0e34\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e02\u0e19\u0e32\u0e14\u0e22\u0e48\u0e2d\u0e21\u0e08\u0e36\u0e07\u0e21\u0e35\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e44\u0e1b\u0e2a\u0e39\u0e48\u0e2a\u0e20\u0e32\u0e1e\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e01\u0e25\u0e32\u0e07\u0e41\u0e08\u0e49\u0e07\u0e14\u0e49\u0e27\u0e22 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49\u0e41\u0e19\u0e27\u0e04\u0e34\u0e14\u0e02\u0e2d\u0e07\u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17\u0e0b\u0e34\u0e15\u0e35\u0e49\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e2d\u0e31\u0e08\u0e09\u0e23\u0e34\u0e22\u0e30\u0e01\u0e47\u0e21\u0e35\u0e01\u0e32\u0e23\u0e27\u0e31\u0e14\u0e1e\u0e32\u0e23\u0e32\u0e21\u0e34\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e20\u0e32\u0e1e\u0e20\u0e39\u0e21\u0e34\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e02\u0e19\u0e32\u0e14\u0e22\u0e48\u0e2d\u0e21\u0e01\u0e25\u0e32\u0e07\u0e41\u0e08\u0e49\u0e07\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e2a\u0e20\u0e32\u0e1e\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1a\u0e23\u0e23\u0e40\u0e17\u0e32\u0e1b\u0e23\u0e32\u0e01\u0e0f\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e40\u0e0a\u0e48\u0e19 \u0e04\u0e25\u0e37\u0e48\u0e19\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-698f8cd elementor-widget elementor-widget-text-editor\" data-id=\"698f8cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>\u0e14\u0e31\u0e0a\u0e19\u0e35\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e04\u0e27\u0e32\u0e21\u0e40\u0e04\u0e23\u0e35\u0e22\u0e14\u0e08\u0e32\u0e01\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 (Heat Stress)<\/strong><br \/>\u0e14\u0e31\u0e0a\u0e19\u0e35 WBGT (Wet Bulb Globe Temperature) \u0e40\u0e1b\u0e47\u0e19\u0e04\u0e48\u0e32\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e02\u0e2d\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22\u0e21\u0e19\u0e38\u0e29\u0e22\u0e4c\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a\u0e44\u0e14\u0e49\u0e43\u0e19\u0e2a\u0e20\u0e32\u0e1e\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e19\u0e31\u0e49\u0e19\u0e46 \u0e42\u0e14\u0e22\u0e04\u0e33\u0e19\u0e36\u0e07\u0e16\u0e36\u0e07\u0e1b\u0e31\u0e08\u0e08\u0e31\u0e22\u0e2b\u0e25\u0e32\u0e22\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e17\u0e35\u0e48\u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e15\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e0a\u0e48\u0e19 \u0e2d\u0e38\u0e13\u0e2b\u0e20\u0e39\u0e21\u0e34 \u0e04\u0e27\u0e32\u0e21\u0e0a\u0e37\u0e49\u0e19 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e07\u0e2a\u0e35\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e1a\u0e48\u0e07\u0e0a\u0e35\u0e49\u0e17\u0e35\u0e48\u0e14\u0e35\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07\u0e15\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e40\u0e01\u0e34\u0e14\u0e04\u0e27\u0e32\u0e21\u0e40\u0e04\u0e23\u0e35\u0e22\u0e14\u0e08\u0e32\u0e01\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 (Heat Stress)<\/p><p><strong>\u0e04\u0e48\u0e32 WBGT \u0e04\u0e37\u0e2d\u0e2d\u0e30\u0e44\u0e23<\/strong><br \/>\u0e04\u0e48\u0e32 WBGT (Wet Bulb Globe Temperature) \u0e40\u0e1b\u0e47\u0e19\u0e04\u0e48\u0e32\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e1a\u0e2d\u0e01\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e02\u0e2d\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22\u0e21\u0e19\u0e38\u0e29\u0e22\u0e4c\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a\u0e44\u0e14\u0e49\u0e43\u0e19\u0e2a\u0e20\u0e32\u0e1e\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e19\u0e31\u0e49\u0e19\u0e46 \u0e04\u0e25\u0e49\u0e32\u0e22\u0e46 \u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e2d\u0e36\u0e14\u0e2d\u0e31\u0e14\u0e23\u0e49\u0e2d\u0e19\u0e2d\u0e1a\u0e2d\u0e49\u0e32\u0e27\u0e43\u0e19\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e23\u0e49\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e0a\u0e37\u0e49\u0e19\u0e2a\u0e39\u0e07 \u0e04\u0e48\u0e32 WBGT \u0e19\u0e35\u0e49\u0e04\u0e33\u0e19\u0e27\u0e13\u0e21\u0e32\u0e08\u0e32\u0e01\u0e1b\u0e31\u0e08\u0e08\u0e31\u0e22\u0e2b\u0e25\u0e32\u0e22\u0e2d\u0e22\u0e48\u0e32\u0e07 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e2d\u0e38\u0e13\u0e2b\u0e20\u0e39\u0e21\u0e34\u0e02\u0e2d\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e04\u0e27\u0e32\u0e21\u0e0a\u0e37\u0e49\u0e19 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e07\u0e2a\u0e35\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e41\u0e1c\u0e48\u0e21\u0e32\u0e08\u0e32\u0e01\u0e27\u0e31\u0e15\u0e16\u0e38\u0e23\u0e2d\u0e1a\u0e02\u0e49\u0e32\u0e07<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c2bbf9b elementor-widget elementor-widget-text-editor\" data-id=\"c2bbf9b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>\u0e17\u0e33\u0e44\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e43\u0e0a\u0e49 <\/strong><strong>WBGT?<\/strong><\/p><ul><li><strong>\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e25\u0e38\u0e21\u0e1b\u0e31\u0e08\u0e08\u0e31\u0e22\u0e2b\u0e25\u0e32\u0e22\u0e2d\u0e22\u0e48\u0e32\u0e07:<\/strong> WBGT \u0e04\u0e33\u0e19\u0e36\u0e07\u0e16\u0e36\u0e07\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e13\u0e2b\u0e20\u0e39\u0e21\u0e34 \u0e04\u0e27\u0e32\u0e21\u0e0a\u0e37\u0e49\u0e19 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e07\u0e2a\u0e35\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e31\u0e08\u0e08\u0e31\u0e22\u0e2b\u0e25\u0e31\u0e01\u0e17\u0e35\u0e48\u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e15\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e23\u0e49\u0e2d\u0e19\u0e02\u0e2d\u0e07\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22<\/li><li><strong>\u0e07\u0e48\u0e32\u0e22\u0e15\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e15\u0e35\u0e04\u0e27\u0e32\u0e21:<\/strong> \u0e04\u0e48\u0e32 WBGT \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e19\u0e33\u0e21\u0e32\u0e40\u0e1b\u0e23\u0e35\u0e22\u0e1a\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e01\u0e31\u0e1a\u0e40\u0e01\u0e13\u0e11\u0e4c\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07\u0e44\u0e14\u0e49\u0e07\u0e48\u0e32\u0e22\u0e42\u0e14\u0e22\u0e40\u0e1b\u0e23\u0e35\u0e22\u0e1a\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e04\u0e48\u0e32 WBGT \u0e17\u0e35\u0e48\u0e27\u0e31\u0e14\u0e44\u0e14\u0e49\u0e01\u0e31\u0e1a\u0e40\u0e01\u0e13\u0e11\u0e4c\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49 \u0e40\u0e0a\u0e48\u0e19 \u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19 ISO 7243<\/li><li><strong>\u0e43\u0e0a\u0e49\u0e44\u0e14\u0e49\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c:<\/strong> \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e19\u0e33\u0e44\u0e1b\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07\u0e43\u0e19\u0e2a\u0e20\u0e32\u0e1e\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e17\u0e35\u0e48\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e19 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21, \u0e01\u0e35\u0e2c\u0e32\u0e01\u0e25\u0e32\u0e07\u0e41\u0e08\u0e49\u0e07, \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e01\u0e25\u0e32\u0e07\u0e41\u0e08\u0e49\u0e07<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b9e38b5 elementor-widget elementor-widget-text-editor\" data-id=\"b9e38b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>\u0e17\u0e33\u0e44\u0e21\u0e04\u0e48\u0e32 <\/strong><strong>WBGT \u0e16\u0e36\u0e07\u0e2a\u0e33\u0e04\u0e31\u0e0d<br \/><\/strong>\u0e04\u0e48\u0e32 WBGT \u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e15\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e32 \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e43\u0e19\u0e2a\u0e20\u0e32\u0e1e\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e17\u0e35\u0e48\u0e21\u0e35\u0e2d\u0e38\u0e13\u0e2b\u0e20\u0e39\u0e21\u0e34\u0e2a\u0e39\u0e07 \u0e2b\u0e32\u0e01\u0e04\u0e48\u0e32 WBGT \u0e2a\u0e39\u0e07\u0e40\u0e01\u0e34\u0e19\u0e44\u0e1b \u0e2d\u0e32\u0e08\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e23\u0e1b\u0e48\u0e27\u0e22\u0e08\u0e32\u0e01\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e0a\u0e48\u0e19 \u0e40\u0e1b\u0e47\u0e19\u0e25\u0e21\u0e41\u0e14\u0e14 \u0e2b\u0e23\u0e37\u0e2d\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22\u0e02\u0e32\u0e14\u0e19\u0e49\u0e33\u0e44\u0e14\u0e49 \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e15\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e0a\u0e35\u0e27\u0e34\u0e15<\/p><p><span style=\"color: #ff6600;\"><strong>LSI LASTEM<br \/><\/strong><\/span>LSI LASTEM \u0e44\u0e14\u0e49\u0e1c\u0e25\u0e34\u0e15\u0e0a\u0e38\u0e14\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e2a\u0e20\u0e32\u0e1e\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21 \u0e42\u0e14\u0e22\u0e44\u0e14\u0e49\u0e04\u0e33\u0e19\u0e36\u0e07\u0e16\u0e36\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e17\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e40\u0e0b\u0e19\u0e40\u0e0b\u0e2d\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e2a\u0e20\u0e32\u0e1e\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e17\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e17\u0e35\u0e48\u0e40\u0e23\u0e35\u0e22\u0e01\u0e27\u0e48\u0e32 <strong>Permanent heat stress measuring system<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-445113f\" data-id=\"445113f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-850f435 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"850f435\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-42b5336\" data-id=\"42b5336\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-ef22705\" data-id=\"ef22705\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-26a7036 elementor-widget elementor-widget-spacer\" data-id=\"26a7036\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-24e4b91 elementor-widget elementor-widget-text-editor\" data-id=\"24e4b91\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<span style=\"color: #ff6600;\"><strong>Permanent heat stress measuring system<\/strong><\/span>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d38baa9 elementor-widget elementor-widget-text-editor\" data-id=\"d38baa9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e15\u0e48\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22 2 \u0e2a\u0e48\u0e27\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e04\u0e31\u0e0d \u0e04\u0e37\u0e2d\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e89c81a elementor-widget elementor-widget-text-editor\" data-id=\"e89c81a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>\u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e41\u0e25\u0e30\u0e41\u0e2a\u0e14\u0e07\u0e1c\u0e25\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25: \u0e21\u0e35\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e33\u0e19\u0e27\u0e13\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e40\u0e1a\u0e37\u0e49\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e20\u0e32\u0e22\u0e43\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e04\u0e48\u0e32\u0e15\u0e31\u0e27\u0e0a\u0e35\u0e49\u0e27\u0e31\u0e14\u0e17\u0e32\u0e07\u0e2a\u0e20\u0e32\u0e1e\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e15\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e40\u0e1a\u0e37\u0e49\u0e2d\u0e07\u0e15\u0e49\u0e19<\/li><li>\u0e0a\u0e38\u0e14\u0e40\u0e0b\u0e19\u0e40\u0e0b\u0e2d\u0e23\u0e4c: \u0e17\u0e33\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e27\u0e31\u0e14\u0e04\u0e48\u0e32\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e17\u0e35\u0e48\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e04\u0e33\u0e19\u0e27\u0e13\u0e14\u0e31\u0e0a\u0e19\u0e35\u0e02\u0e2d\u0e07\u0e2a\u0e20\u0e32\u0e1e\u0e20\u0e39\u0e21\u0e34\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e02\u0e19\u0e32\u0e14\u0e22\u0e48\u0e2d\u0e21 \u0e42\u0e14\u0e22\u0e2d\u0e49\u0e32\u0e07\u0e2d\u0e34\u0e07\u0e15\u0e32\u0e21\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19 ISO<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dbcd37a elementor-widget elementor-widget-text-editor\" data-id=\"dbcd37a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49\u0e22\u0e31\u0e07\u0e21\u0e35\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c (PC programs) \u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e33\u0e19\u0e27\u0e13\u0e14\u0e31\u0e0a\u0e19\u0e35\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e0b\u0e31\u0e1a\u0e0b\u0e49\u0e2d\u0e19\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19 \u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e04\u0e33\u0e19\u0e27\u0e13\u0e44\u0e14\u0e49\u0e42\u0e14\u0e22\u0e15\u0e23\u0e07\u0e08\u0e32\u0e01\u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e41\u0e25\u0e30\u0e41\u0e2a\u0e14\u0e07\u0e1c\u0e25\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e0a\u0e48\u0e27\u0e22\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e2a\u0e20\u0e32\u0e1e\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e17\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e41\u0e25\u0e30\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e25\u0e38\u0e21\u0e22\u0e34\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19 \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-80f51e9\" data-id=\"80f51e9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d02c848 elementor-widget elementor-widget-image\" data-id=\"d02c848\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"357\" height=\"632\" src=\"https:\/\/entechsi.com\/wp-content\/uploads\/2024\/08\/\u0e2a\u0e20\u0e32\u0e1e\u0e20\u0e39\u0e21\u0e34\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e02\u0e19\u0e32\u0e14\u0e22\u0e48\u0e2d\u0e21-Microclimate-\u0e01\u0e31\u0e1a\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22-04.jpg\" class=\"attachment-full size-full wp-image-11230\" alt=\"\u0e2a\u0e20\u0e32\u0e1e\u0e20\u0e39\u0e21\u0e34\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e02\u0e19\u0e32\u0e14\u0e22\u0e48\u0e2d\u0e21 (microclimate) \u0e01\u0e31\u0e1a\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 04\" srcset=\"https:\/\/entechsi.com\/wp-content\/uploads\/2024\/08\/\u0e2a\u0e20\u0e32\u0e1e\u0e20\u0e39\u0e21\u0e34\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e02\u0e19\u0e32\u0e14\u0e22\u0e48\u0e2d\u0e21-Microclimate-\u0e01\u0e31\u0e1a\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22-04.jpg 357w, https:\/\/entechsi.com\/wp-content\/uploads\/2024\/08\/\u0e2a\u0e20\u0e32\u0e1e\u0e20\u0e39\u0e21\u0e34\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e02\u0e19\u0e32\u0e14\u0e22\u0e48\u0e2d\u0e21-Microclimate-\u0e01\u0e31\u0e1a\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22-04-169x300.jpg 169w\" sizes=\"(max-width: 357px) 100vw, 357px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-7cd9239\" data-id=\"7cd9239\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b106a40 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b106a40\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-2cf4d8b\" data-id=\"2cf4d8b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-38f1114\" data-id=\"38f1114\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ae7e2b7 elementor-widget elementor-widget-text-editor\" data-id=\"ae7e2b7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e02\u0e2d\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e01\u0e07\u0e32\u0e19\u0e41\u0e1a\u0e1a\u0e40\u0e23\u0e35\u0e22\u0e25\u0e44\u0e17\u0e21\u0e4c \u0e43\u0e19\u0e2a\u0e20\u0e32\u0e27\u0e30\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e40\u0e04\u0e23\u0e35\u0e22\u0e14\u0e08\u0e32\u0e01\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e2a\u0e39\u0e07 \u0e42\u0e14\u0e22 LSI LASTEM \u0e44\u0e14\u0e49\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e02\u0e19\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48 \u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e2d\u0e07\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e2a\u0e20\u0e32\u0e27\u0e30\u0e04\u0e27\u0e32\u0e21\u0e40\u0e04\u0e23\u0e35\u0e22\u0e14\u0e08\u0e32\u0e01\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e13 \u0e08\u0e38\u0e14\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07 \u0e42\u0e14\u0e22\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22\u0e42\u0e21\u0e14\u0e39\u0e25 Satellite radio \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e15\u0e23\u0e27\u0e08\u0e27\u0e31\u0e14\u0e2d\u0e38\u0e13\u0e2b\u0e20\u0e39\u0e21\u0e34\u0e02\u0e2d\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e04\u0e27\u0e32\u0e21\u0e0a\u0e37\u0e49\u0e19\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e17\u0e18\u0e4c \u0e2d\u0e38\u0e13\u0e2b\u0e20\u0e39\u0e21\u0e34\u0e01\u0e32\u0e23\u0e41\u0e1c\u0e48\u0e23\u0e31\u0e07\u0e2a\u0e35 \u0e2d\u0e38\u0e13\u0e2b\u0e20\u0e39\u0e21\u0e34\u0e40\u0e1b\u0e35\u0e22\u0e01 \u0e42\u0e14\u0e22\u0e04\u0e33\u0e19\u0e27\u0e13\u0e14\u0e31\u0e0a\u0e19\u0e35\u0e04\u0e27\u0e32\u0e21\u0e40\u0e04\u0e23\u0e35\u0e22\u0e14\u0e08\u0e32\u0e01\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e2b\u0e25\u0e32\u0e22\u0e1b\u0e31\u0e08\u0e08\u0e31\u0e22 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e14\u0e31\u0e0a\u0e19\u0e35 WBGT \u0e15\u0e32\u0e21\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19 ISO7243 \u0e14\u0e49\u0e27\u0e22 \u0e42\u0e14\u0e22\u0e41\u0e15\u0e48\u0e25\u0e30\u0e42\u0e21\u0e14\u0e39\u0e25\u0e08\u0e30\u0e2a\u0e48\u0e07\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e44\u0e1b\u0e22\u0e31\u0e07\u0e15\u0e31\u0e27\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e2b\u0e25\u0e31\u0e01 \u0e0b\u0e36\u0e48\u0e07\u0e08\u0e30\u0e2a\u0e48\u0e07\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e41\u0e1a\u0e1a\u0e40\u0e23\u0e35\u0e22\u0e25\u0e44\u0e17\u0e21\u0e4c\u0e44\u0e1b\u0e22\u0e31\u0e07\u0e2b\u0e49\u0e2d\u0e07\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21 \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13\u0e40\u0e15\u0e37\u0e2d\u0e19\u0e1c\u0e48\u0e32\u0e19 SMS \u0e2b\u0e23\u0e37\u0e2d\u0e2d\u0e35\u0e40\u0e21\u0e25 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d\u0e01\u0e31\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e15\u0e37\u0e2d\u0e19\u0e20\u0e31\u0e22\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e48\u0e07\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e44\u0e1b\u0e22\u0e31\u0e07\u0e23\u0e30\u0e1a\u0e1a SCADA \u0e1c\u0e48\u0e32\u0e19\u0e42\u0e1b\u0e23\u0e42\u0e15\u0e04\u0e2d\u0e25 Modbus RTU \/ TCP \u0e14\u0e49\u0e27\u0e22\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-17eb2b0\" data-id=\"17eb2b0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-00472e3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"00472e3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-9f2e112\" data-id=\"9f2e112\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-75c041d\" data-id=\"75c041d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-260daf9 elementor-widget elementor-widget-image\" data-id=\"260daf9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"572\" height=\"470\" src=\"https:\/\/entechsi.com\/wp-content\/uploads\/2024\/08\/\u0e2a\u0e20\u0e32\u0e1e\u0e20\u0e39\u0e21\u0e34\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e02\u0e19\u0e32\u0e14\u0e22\u0e48\u0e2d\u0e21-Microclimate-\u0e01\u0e31\u0e1a\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22-05.jpg\" class=\"attachment-full size-full wp-image-11232\" alt=\"\u0e2a\u0e20\u0e32\u0e1e\u0e20\u0e39\u0e21\u0e34\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e02\u0e19\u0e32\u0e14\u0e22\u0e48\u0e2d\u0e21 (microclimate) \u0e01\u0e31\u0e1a\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 05\" srcset=\"https:\/\/entechsi.com\/wp-content\/uploads\/2024\/08\/\u0e2a\u0e20\u0e32\u0e1e\u0e20\u0e39\u0e21\u0e34\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e02\u0e19\u0e32\u0e14\u0e22\u0e48\u0e2d\u0e21-Microclimate-\u0e01\u0e31\u0e1a\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22-05.jpg 572w, https:\/\/entechsi.com\/wp-content\/uploads\/2024\/08\/\u0e2a\u0e20\u0e32\u0e1e\u0e20\u0e39\u0e21\u0e34\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e02\u0e19\u0e32\u0e14\u0e22\u0e48\u0e2d\u0e21-Microclimate-\u0e01\u0e31\u0e1a\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22-05-300x247.jpg 300w\" sizes=\"(max-width: 572px) 100vw, 572px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-ee82485\" data-id=\"ee82485\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-12a0093 elementor-widget elementor-widget-text-editor\" data-id=\"12a0093\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<strong>\u0e23\u0e30\u0e1a\u0e1a\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e04\u0e27\u0e32\u0e21\u0e40\u0e04\u0e23\u0e35\u0e22\u0e14\u0e08\u0e32\u0e01\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e1a\u0e32\u0e22\u0e17\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e41\u0e1a\u0e1a\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07<\/strong>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-07aa4c1 elementor-widget elementor-widget-text-editor\" data-id=\"07aa4c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19 ISO7243 \u0e41\u0e25\u0e30 ISO7726<\/li><li>\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22\u0e0a\u0e38\u0e14\u0e42\u0e21\u0e14\u0e39\u0e25\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e27\u0e31\u0e14\u0e2b\u0e25\u0e32\u0e22\u0e1e\u0e32\u0e23\u0e32\u0e21\u0e34\u0e40\u0e15\u0e2d\u0e23\u0e4c (\u0e2d\u0e38\u0e13\u0e2b\u0e20\u0e39\u0e21\u0e34 Globe temperature \u0e2d\u0e38\u0e13\u0e2b\u0e20\u0e39\u0e21\u0e34\u0e40\u0e1b\u0e35\u0e22\u0e01) \u0e41\u0e25\u0e30\u0e21\u0e35\u0e40\u0e0b\u0e19\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21 (\u0e2d\u0e38\u0e13\u0e2b\u0e20\u0e39\u0e21\u0e34\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e04\u0e27\u0e32\u0e21\u0e0a\u0e37\u0e49\u0e19\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e17\u0e18\u0e4c \u0e01\u0e32\u0e23\u0e41\u0e1c\u0e48\u0e23\u0e31\u0e07\u0e2a\u0e35\u0e08\u0e32\u0e01\u0e14\u0e27\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c \u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e25\u0e21 \u0e2f\u0e25\u0e2f)<\/li><li>\u0e04\u0e33\u0e19\u0e27\u0e13\u0e04\u0e48\u0e32\u0e14\u0e31\u0e0a\u0e19\u0e35 WBGT \u0e41\u0e1a\u0e1a\u0e40\u0e23\u0e35\u0e22\u0e25\u0e44\u0e17\u0e21\u0e4c \u0e15\u0e32\u0e21\u0e21\u0e32\u0e23\u0e15\u0e23\u0e10\u0e32\u0e19 ISO ISO7243<\/li><li>\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e41\u0e1a\u0e1a\u0e16\u0e32\u0e27\u0e23 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e41\u0e1a\u0e1a\u0e40\u0e23\u0e35\u0e22\u0e25\u0e44\u0e17\u0e21\u0e4c<\/li><li>\u0e17\u0e19\u0e17\u0e32\u0e19\u0e15\u0e48\u0e2d\u0e2a\u0e20\u0e32\u0e1e\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e17\u0e35\u0e48\u0e23\u0e38\u0e19\u0e41\u0e23\u0e07<\/li><li>\u0e41\u0e2a\u0e14\u0e07\u0e1c\u0e25\u0e41\u0e1a\u0e1a\u0e40\u0e23\u0e35\u0e22\u0e25\u0e44\u0e17\u0e21\u0e4c\u0e1a\u0e19\u0e41\u0e14\u0e0a\u0e1a\u0e2d\u0e23\u0e4c\u0e14\u0e17\u0e35\u0e48\u0e2b\u0e49\u0e2d\u0e07\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21 \u0e1c\u0e48\u0e32\u0e19\u0e40\u0e0b\u0e34\u0e23\u0e4c\u0e1f\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e15\u0e31\u0e27\u0e01\u0e25\u0e32\u0e07 M QTT<\/li><li>\u0e21\u0e35\u0e23\u0e30\u0e1a\u0e1a\u0e41\u0e08\u0e49\u0e07\u0e40\u0e15\u0e37\u0e2d\u0e19\u0e1c\u0e48\u0e32\u0e19 SMS \u0e41\u0e25\u0e30\u0e2d\u0e35\u0e40\u0e21\u0e25<\/li><li>\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e48\u0e07\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e44\u0e1b\u0e22\u0e31\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e15\u0e37\u0e2d\u0e19\u0e20\u0e31\u0e22\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e44\u0e14\u0e49<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-e2fff45\" data-id=\"e2fff45\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5e56775 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5e56775\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-859963b\" data-id=\"859963b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-a9138ee\" data-id=\"a9138ee\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-036e625 elementor-widget elementor-widget-text-editor\" data-id=\"036e625\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>\u0e2a\u0e19\u0e43\u0e08\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d :<\/strong> \u0e04\u0e38\u0e13\u0e1b\u0e17\u0e34\u0e15\u0e15\u0e32 \u0e42\u0e17\u0e23. 088-924-9644 \u0e2b\u0e23\u0e37\u0e2d 092-258-1144 \u0e2b\u0e23\u0e37\u0e2d Line ID : @entechsi<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-908fba7\" data-id=\"908fba7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u0e2a\u0e20\u0e32\u0e1e\u0e20\u0e39\u0e21\u0e34\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e02\u0e19\u0e32\u0e14\u0e22\u0e48\u0e2d\u0e21 (Microclimate) \u0e2a\u0e37\u0e48\u0e2d\u0e16\u0e36\u0e07\u0e2a\u0e20\u0e32\u0e1e\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e02\u0e19\u0e32\u0e14\u0e22\u0e48\u0e2d\u0e21\u0e20\u0e32\u0e22\u0e43\u0e19\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e17\u0e35\u0e48\u0e01\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e34\u0e14\u0e42\u0e25\u0e48\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e17\u0e35\u0e48\u0e42\u0e25\u0e48\u0e07 \u0e23\u0e27\u0e21\u0e08\u0e19\u0e16\u0e36\u0e07\u0e2a\u0e20\u0e32\u0e1e\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e02\u0e2d\u0e07\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22\u0e1b\u0e31\u0e08\u0e08\u0e31\u0e22\u0e17\u0e32\u0e07\u0e01\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e2b\u0e25\u0e32\u0e22\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e17\u0e35\u0e48\u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e15\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e17\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e02\u0e2d\u0e07\u0e21\u0e19\u0e38\u0e29\u0e22\u0e4c \u0e40\u0e0a\u0e48\u0e19 \u0e2d\u0e38\u0e13\u0e2b\u0e20\u0e39\u0e21\u0e34 \u0e04\u0e27\u0e32\u0e21\u0e0a\u0e37\u0e49\u0e19\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e17\u0e18\u0e4c \u0e2d\u0e38\u0e13\u0e2b\u0e20\u0e39\u0e21\u0e34\u0e40\u0e09\u0e25\u0e35\u0e48\u0e22\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1c\u0e48\u0e23\u0e31\u0e07\u0e2a\u0e35\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e25\u0e21 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19 \u0e40\u0e14\u0e34\u0e21\u0e17\u0e35\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e2a\u0e20\u0e32\u0e1e\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e17\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e21\u0e38\u0e48\u0e07\u0e40\u0e19\u0e49\u0e19\u0e44\u0e1b\u0e17\u0e35\u0e48\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e02\u0e2d\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e14\u0e31\u0e07\u0e19\u0e31\u0e49\u0e19 \u0e2a\u0e20\u0e32\u0e1e\u0e20\u0e39\u0e21\u0e34\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e02\u0e19\u0e32\u0e14\u0e22\u0e48\u0e2d\u0e21 (Microclimate) \u0e08\u0e36\u0e07\u0e16\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e43\u0e19\u0e1b\u0e31\u0e08\u0e08\u0e31\u0e22\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07\u0e17\u0e32\u0e07\u0e01\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e17\u0e35\u0e48\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e2b\u0e25\u0e32\u0e22\u0e09\u0e1a\u0e31\u0e1a\u0e02\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49 \u0e0b\u0e36\u0e48\u0e07\u0e43\u0e19\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e22\u0e2d\u0e21\u0e23\u0e31\u0e1a\u0e01\u0e31\u0e19\u0e14\u0e35\u0e27\u0e48\u0e32 \u0e2a\u0e20\u0e32\u0e1e\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e0a\u0e37\u0e49\u0e19\u0e43\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e15\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e2a\u0e20\u0e32\u0e27\u0e30\u0e1b\u0e01\u0e15\u0e34 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e15\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e02\u0e2d\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e43\u0e19\u0e2a\u0e20\u0e32\u0e27\u0e30\u0e17\u0e35\u0e48\u0e23\u0e38\u0e19\u0e41\u0e23\u0e07 \u0e15\u0e32\u0e21\u0e2b\u0e25\u0e31\u0e01\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e41\u0e25\u0e49\u0e27 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e2a\u0e20\u0e32\u0e1e\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e17\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e21\u0e35\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22\u0e2b\u0e25\u0e31\u0e01\u0e04\u0e37\u0e2d \u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e1a\u0e32\u0e22\u0e17\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e14\u0e35\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14 \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e15\u0e48\u0e2d\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e19\u0e48\u0e32\u0e2d\u0e22\u0e39\u0e48\u0e02\u0e2d\u0e07\u0e2a\u0e20\u0e32\u0e1e\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21 \u0e43\u0e19\u0e2a\u0e20\u0e32\u0e1e\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e23\u0e38\u0e19\u0e41\u0e23\u0e07 (\u0e17\u0e31\u0e49\u0e07\u0e23\u0e49\u0e2d\u0e19\u0e08\u0e31\u0e14\u0e41\u0e25\u0e30\u0e40\u0e22\u0e47\u0e19\u0e08\u0e31\u0e14) \u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22\u0e2b\u0e25\u0e31\u0e01\u0e04\u0e37\u0e2d \u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e1c\u0e39\u0e49\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e08\u0e32\u0e01\u0e2a\u0e20\u0e32\u0e27\u0e30\u0e17\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e31\u0e19\u0e15\u0e23\u0e32\u0e22 \u0e0b\u0e36\u0e48\u0e07\u0e2d\u0e32\u0e08\u0e01\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e23\u0e42\u0e23\u0e04\u0e25\u0e21\u0e23\u0e49\u0e2d\u0e19 (heat stroke) (\u0e43\u0e19\u0e2a\u0e20\u0e32\u0e1e\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e17\u0e35\u0e48\u0e23\u0e49\u0e2d\u0e19\u0e08\u0e31\u0e14) \u0e2d\u0e32\u0e01\u0e32\u0e23\u0e2a\u0e20\u0e32\u0e27\u0e30\u0e15\u0e31\u0e27\u0e40\u0e22\u0e47\u0e19 (\u0e43\u0e19\u0e2a\u0e20\u0e32\u0e1e\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e41\u0e1a\u0e1a\u0e40\u0e22\u0e47\u0e19) \u0e14\u0e31\u0e07\u0e19\u0e31\u0e49\u0e19\u0e43\u0e19\u0e01\u0e23\u0e13\u0e35\u0e17\u0e35\u0e48\u0e01\u0e25\u0e48\u0e32\u0e27\u0e21\u0e32\u0e02\u0e49\u0e32\u0e07\u0e15\u0e49\u0e19 \u0e01\u0e32\u0e23\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e2a\u0e20\u0e32\u0e1e\u0e20\u0e39\u0e21\u0e34\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e02\u0e19\u0e32\u0e14\u0e22\u0e48\u0e2d\u0e21 (Microclimate) \u0e08\u0e36\u0e07\u0e21\u0e38\u0e48\u0e07\u0e40\u0e19\u0e49\u0e19\u0e44\u0e1b\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07 \u0e42\u0e14\u0e22\u0e40\u0e1b\u0e23\u0e35\u0e22\u0e1a\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e2a\u0e20\u0e32\u0e1e\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e01\u0e31\u0e1a\u0e2a\u0e20\u0e32\u0e1e\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e17\u0e35\u0e48\u0e2d\u0e32\u0e08\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e31\u0e19\u0e15\u0e23\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e17\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e02\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e08\u0e30\u0e43\u0e0a\u0e49\u0e01\u0e32\u0e23\u0e04\u0e33\u0e19\u0e27\u0e13\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e15\u0e32\u0e21\u0e1b\u0e31\u0e08\u0e08\u0e31\u0e22\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e40\u0e23\u0e35\u0e22\u0e01\u0e27\u0e48\u0e32\u0e14\u0e31\u0e0a\u0e19\u0e35\u0e2a\u0e20\u0e32\u0e1e\u0e20\u0e39\u0e21\u0e34\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e02\u0e19\u0e32\u0e14\u0e22\u0e48\u0e2d\u0e21 (microclimatic indexes) \u0e21\u0e35\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e38\u0e1b\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e20\u0e32\u0e1e\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22\u0e15\u0e31\u0e27\u0e41\u0e1b\u0e23\u0e2b\u0e25\u0e32\u0e22\u0e2d\u0e22\u0e48\u0e32\u0e07 (\u0e1b\u0e23\u0e34\u0e21\u0e32\u0e13\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 &#8211; \u0e04\u0e27\u0e32\u0e21\u0e0a\u0e37\u0e49\u0e19 [&hellip;]<\/p>\n","protected":false},"author":150,"featured_media":11222,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[243],"tags":[961,963,964,962],"class_list":["post-11221","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","tag-microclimate","tag-wbgt","tag-wet-bulb-globe-temperature","tag-962"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0e2a\u0e20\u0e32\u0e1e\u0e20\u0e39\u0e21\u0e34\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e02\u0e19\u0e32\u0e14\u0e22\u0e48\u0e2d\u0e21 (Microclimate) \u0e01\u0e31\u0e1a\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 - ENTECH SI CO., LTD.<\/title>\n<meta name=\"description\" content=\"\u0e40\u0e14\u0e34\u0e21\u0e17\u0e35\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e2a\u0e20\u0e32\u0e1e\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e17\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e21\u0e38\u0e48\u0e07\u0e40\u0e19\u0e49\u0e19\u0e44\u0e1b\u0e17\u0e35\u0e48\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e02\u0e2d\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e14\u0e31\u0e07\u0e19\u0e31\u0e49\u0e19 \u0e2a\u0e20\u0e32\u0e1e\u0e20\u0e39\u0e21\u0e34\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e02\u0e19\u0e32\u0e14\u0e22\u0e48\u0e2d\u0e21 (Microclimate) \u0e08\u0e36\u0e07\u0e16\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e43\u0e19\u0e1b\u0e31\u0e08\u0e08\u0e31\u0e22\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07\u0e17\u0e32\u0e07\u0e01\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e17\u0e35\u0e48\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e2b\u0e25\u0e32\u0e22\u0e09\u0e1a\u0e31\u0e1a\u0e02\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/entechsi.com\/en\/%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%ad%e0%b8%b2%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%82%e0%b8%99%e0%b8%b2%e0%b8%94%e0%b8%a2%e0%b9%88%e0%b8%ad%e0%b8%a1-microclim\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e2a\u0e20\u0e32\u0e1e\u0e20\u0e39\u0e21\u0e34\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e02\u0e19\u0e32\u0e14\u0e22\u0e48\u0e2d\u0e21 (Microclimate) \u0e01\u0e31\u0e1a\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 - ENTECH SI CO., LTD.\" \/>\n<meta property=\"og:description\" content=\"\u0e40\u0e14\u0e34\u0e21\u0e17\u0e35\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e2a\u0e20\u0e32\u0e1e\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e17\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e21\u0e38\u0e48\u0e07\u0e40\u0e19\u0e49\u0e19\u0e44\u0e1b\u0e17\u0e35\u0e48\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e02\u0e2d\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e14\u0e31\u0e07\u0e19\u0e31\u0e49\u0e19 \u0e2a\u0e20\u0e32\u0e1e\u0e20\u0e39\u0e21\u0e34\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e02\u0e19\u0e32\u0e14\u0e22\u0e48\u0e2d\u0e21 (Microclimate) \u0e08\u0e36\u0e07\u0e16\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e43\u0e19\u0e1b\u0e31\u0e08\u0e08\u0e31\u0e22\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07\u0e17\u0e32\u0e07\u0e01\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e17\u0e35\u0e48\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e2b\u0e25\u0e32\u0e22\u0e09\u0e1a\u0e31\u0e1a\u0e02\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\" \/>\n<meta property=\"og:url\" content=\"https:\/\/entechsi.com\/en\/%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%ad%e0%b8%b2%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%82%e0%b8%99%e0%b8%b2%e0%b8%94%e0%b8%a2%e0%b9%88%e0%b8%ad%e0%b8%a1-microclim\/\" \/>\n<meta property=\"og:site_name\" content=\"ENTECH SI CO., LTD.\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-15T01:38:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-15T03:15:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/entechsi.com\/wp-content\/uploads\/2024\/08\/\u0e2a\u0e20\u0e32\u0e1e\u0e20\u0e39\u0e21\u0e34\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e02\u0e19\u0e32\u0e14\u0e22\u0e48\u0e2d\u0e21-Microclimate-\u0e01\u0e31\u0e1a\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22-banner.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"468\" \/>\n\t<meta property=\"og:image:height\" content=\"308\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"entech_admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"entech_admin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/entechsi.com\\\/en\\\/%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%ad%e0%b8%b2%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%82%e0%b8%99%e0%b8%b2%e0%b8%94%e0%b8%a2%e0%b9%88%e0%b8%ad%e0%b8%a1-microclim\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/entechsi.com\\\/en\\\/%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%ad%e0%b8%b2%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%82%e0%b8%99%e0%b8%b2%e0%b8%94%e0%b8%a2%e0%b9%88%e0%b8%ad%e0%b8%a1-microclim\\\/\"},\"author\":{\"name\":\"entech_admin\",\"@id\":\"https:\\\/\\\/entechsi.com\\\/en\\\/th\\\/#\\\/schema\\\/person\\\/00bd16e1c5f992fbba3a8654f2bf4557\"},\"headline\":\"\u0e2a\u0e20\u0e32\u0e1e\u0e20\u0e39\u0e21\u0e34\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e02\u0e19\u0e32\u0e14\u0e22\u0e48\u0e2d\u0e21 (Microclimate) \u0e01\u0e31\u0e1a\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\",\"datePublished\":\"2024-08-15T01:38:45+00:00\",\"dateModified\":\"2024-08-15T03:15:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/entechsi.com\\\/en\\\/%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%ad%e0%b8%b2%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%82%e0%b8%99%e0%b8%b2%e0%b8%94%e0%b8%a2%e0%b9%88%e0%b8%ad%e0%b8%a1-microclim\\\/\"},\"wordCount\":78,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/entechsi.com\\\/en\\\/th\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/entechsi.com\\\/en\\\/%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%ad%e0%b8%b2%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%82%e0%b8%99%e0%b8%b2%e0%b8%94%e0%b8%a2%e0%b9%88%e0%b8%ad%e0%b8%a1-microclim\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/entechsi.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/\u0e2a\u0e20\u0e32\u0e1e\u0e20\u0e39\u0e21\u0e34\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e02\u0e19\u0e32\u0e14\u0e22\u0e48\u0e2d\u0e21-Microclimate-\u0e01\u0e31\u0e1a\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22-banner.jpg\",\"keywords\":[\"Microclimate\",\"WBGT\",\"Wet Bulb Globe Temperature\",\"\u0e2a\u0e20\u0e32\u0e1e\u0e20\u0e39\u0e21\u0e34\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e02\u0e19\u0e32\u0e14\u0e22\u0e48\u0e2d\u0e21\"],\"articleSection\":[\"Blog\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/entechsi.com\\\/en\\\/%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%ad%e0%b8%b2%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%82%e0%b8%99%e0%b8%b2%e0%b8%94%e0%b8%a2%e0%b9%88%e0%b8%ad%e0%b8%a1-microclim\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/entechsi.com\\\/en\\\/%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%ad%e0%b8%b2%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%82%e0%b8%99%e0%b8%b2%e0%b8%94%e0%b8%a2%e0%b9%88%e0%b8%ad%e0%b8%a1-microclim\\\/\",\"url\":\"https:\\\/\\\/entechsi.com\\\/en\\\/%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%ad%e0%b8%b2%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%82%e0%b8%99%e0%b8%b2%e0%b8%94%e0%b8%a2%e0%b9%88%e0%b8%ad%e0%b8%a1-microclim\\\/\",\"name\":\"\u0e2a\u0e20\u0e32\u0e1e\u0e20\u0e39\u0e21\u0e34\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e02\u0e19\u0e32\u0e14\u0e22\u0e48\u0e2d\u0e21 (Microclimate) \u0e01\u0e31\u0e1a\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 - ENTECH SI CO., LTD.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/entechsi.com\\\/en\\\/th\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/entechsi.com\\\/en\\\/%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%ad%e0%b8%b2%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%82%e0%b8%99%e0%b8%b2%e0%b8%94%e0%b8%a2%e0%b9%88%e0%b8%ad%e0%b8%a1-microclim\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/entechsi.com\\\/en\\\/%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%ad%e0%b8%b2%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%82%e0%b8%99%e0%b8%b2%e0%b8%94%e0%b8%a2%e0%b9%88%e0%b8%ad%e0%b8%a1-microclim\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/entechsi.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/\u0e2a\u0e20\u0e32\u0e1e\u0e20\u0e39\u0e21\u0e34\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e02\u0e19\u0e32\u0e14\u0e22\u0e48\u0e2d\u0e21-Microclimate-\u0e01\u0e31\u0e1a\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22-banner.jpg\",\"datePublished\":\"2024-08-15T01:38:45+00:00\",\"dateModified\":\"2024-08-15T03:15:11+00:00\",\"description\":\"\u0e40\u0e14\u0e34\u0e21\u0e17\u0e35\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e2a\u0e20\u0e32\u0e1e\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e17\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e21\u0e38\u0e48\u0e07\u0e40\u0e19\u0e49\u0e19\u0e44\u0e1b\u0e17\u0e35\u0e48\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e02\u0e2d\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e14\u0e31\u0e07\u0e19\u0e31\u0e49\u0e19 \u0e2a\u0e20\u0e32\u0e1e\u0e20\u0e39\u0e21\u0e34\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e02\u0e19\u0e32\u0e14\u0e22\u0e48\u0e2d\u0e21 (Microclimate) \u0e08\u0e36\u0e07\u0e16\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e43\u0e19\u0e1b\u0e31\u0e08\u0e08\u0e31\u0e22\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07\u0e17\u0e32\u0e07\u0e01\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e17\u0e35\u0e48\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e2b\u0e25\u0e32\u0e22\u0e09\u0e1a\u0e31\u0e1a\u0e02\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/entechsi.com\\\/en\\\/%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%ad%e0%b8%b2%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%82%e0%b8%99%e0%b8%b2%e0%b8%94%e0%b8%a2%e0%b9%88%e0%b8%ad%e0%b8%a1-microclim\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/entechsi.com\\\/en\\\/%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%ad%e0%b8%b2%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%82%e0%b8%99%e0%b8%b2%e0%b8%94%e0%b8%a2%e0%b9%88%e0%b8%ad%e0%b8%a1-microclim\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/entechsi.com\\\/en\\\/%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%ad%e0%b8%b2%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%82%e0%b8%99%e0%b8%b2%e0%b8%94%e0%b8%a2%e0%b9%88%e0%b8%ad%e0%b8%a1-microclim\\\/#primaryimage\",\"url\":\"https:\\\/\\\/entechsi.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/\u0e2a\u0e20\u0e32\u0e1e\u0e20\u0e39\u0e21\u0e34\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e02\u0e19\u0e32\u0e14\u0e22\u0e48\u0e2d\u0e21-Microclimate-\u0e01\u0e31\u0e1a\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22-banner.jpg\",\"contentUrl\":\"https:\\\/\\\/entechsi.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/\u0e2a\u0e20\u0e32\u0e1e\u0e20\u0e39\u0e21\u0e34\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e02\u0e19\u0e32\u0e14\u0e22\u0e48\u0e2d\u0e21-Microclimate-\u0e01\u0e31\u0e1a\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22-banner.jpg\",\"width\":468,\"height\":308,\"caption\":\"\u0e2a\u0e20\u0e32\u0e1e\u0e20\u0e39\u0e21\u0e34\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e02\u0e19\u0e32\u0e14\u0e22\u0e48\u0e2d\u0e21 (microclimate) \u0e01\u0e31\u0e1a\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 Banner\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/entechsi.com\\\/en\\\/%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%ad%e0%b8%b2%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%82%e0%b8%99%e0%b8%b2%e0%b8%94%e0%b8%a2%e0%b9%88%e0%b8%ad%e0%b8%a1-microclim\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/entechsi.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e2a\u0e20\u0e32\u0e1e\u0e20\u0e39\u0e21\u0e34\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e02\u0e19\u0e32\u0e14\u0e22\u0e48\u0e2d\u0e21 (Microclimate) \u0e01\u0e31\u0e1a\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/entechsi.com\\\/en\\\/th\\\/#website\",\"url\":\"https:\\\/\\\/entechsi.com\\\/en\\\/th\\\/\",\"name\":\"ENTECH SI CO., LTD.\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/entechsi.com\\\/en\\\/th\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/entechsi.com\\\/en\\\/th\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/entechsi.com\\\/en\\\/th\\\/#organization\",\"name\":\"ENTECH SI CO., LTD.\",\"url\":\"https:\\\/\\\/entechsi.com\\\/en\\\/th\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/entechsi.com\\\/en\\\/th\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/entechsi.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/entechsi.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/logo.png\",\"width\":289,\"height\":30,\"caption\":\"ENTECH SI CO., LTD.\"},\"image\":{\"@id\":\"https:\\\/\\\/entechsi.com\\\/en\\\/th\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/entechsi.com\\\/en\\\/th\\\/#\\\/schema\\\/person\\\/00bd16e1c5f992fbba3a8654f2bf4557\",\"name\":\"entech_admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/682736f2f76be8408aafea754aea7735?s=96&#038;r=g&#038;d=mm\",\"url\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/682736f2f76be8408aafea754aea7735?s=96&#038;r=g&#038;d=mm\",\"contentUrl\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/682736f2f76be8408aafea754aea7735?s=96&#038;r=g&#038;d=mm\",\"caption\":\"entech_admin\"},\"url\":\"https:\\\/\\\/entechsi.com\\\/en\\\/author\\\/entech_admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e2a\u0e20\u0e32\u0e1e\u0e20\u0e39\u0e21\u0e34\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e02\u0e19\u0e32\u0e14\u0e22\u0e48\u0e2d\u0e21 (Microclimate) \u0e01\u0e31\u0e1a\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 - ENTECH SI CO., LTD.","description":"\u0e40\u0e14\u0e34\u0e21\u0e17\u0e35\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e2a\u0e20\u0e32\u0e1e\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e17\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e21\u0e38\u0e48\u0e07\u0e40\u0e19\u0e49\u0e19\u0e44\u0e1b\u0e17\u0e35\u0e48\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e02\u0e2d\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e14\u0e31\u0e07\u0e19\u0e31\u0e49\u0e19 \u0e2a\u0e20\u0e32\u0e1e\u0e20\u0e39\u0e21\u0e34\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e02\u0e19\u0e32\u0e14\u0e22\u0e48\u0e2d\u0e21 (Microclimate) \u0e08\u0e36\u0e07\u0e16\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e43\u0e19\u0e1b\u0e31\u0e08\u0e08\u0e31\u0e22\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07\u0e17\u0e32\u0e07\u0e01\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e17\u0e35\u0e48\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e2b\u0e25\u0e32\u0e22\u0e09\u0e1a\u0e31\u0e1a\u0e02\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/entechsi.com\/en\/%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%ad%e0%b8%b2%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%82%e0%b8%99%e0%b8%b2%e0%b8%94%e0%b8%a2%e0%b9%88%e0%b8%ad%e0%b8%a1-microclim\/","og_locale":"en_US","og_type":"article","og_title":"\u0e2a\u0e20\u0e32\u0e1e\u0e20\u0e39\u0e21\u0e34\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e02\u0e19\u0e32\u0e14\u0e22\u0e48\u0e2d\u0e21 (Microclimate) \u0e01\u0e31\u0e1a\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 - ENTECH SI CO., LTD.","og_description":"\u0e40\u0e14\u0e34\u0e21\u0e17\u0e35\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e2a\u0e20\u0e32\u0e1e\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e17\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e21\u0e38\u0e48\u0e07\u0e40\u0e19\u0e49\u0e19\u0e44\u0e1b\u0e17\u0e35\u0e48\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e02\u0e2d\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e14\u0e31\u0e07\u0e19\u0e31\u0e49\u0e19 \u0e2a\u0e20\u0e32\u0e1e\u0e20\u0e39\u0e21\u0e34\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e02\u0e19\u0e32\u0e14\u0e22\u0e48\u0e2d\u0e21 (Microclimate) \u0e08\u0e36\u0e07\u0e16\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e43\u0e19\u0e1b\u0e31\u0e08\u0e08\u0e31\u0e22\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07\u0e17\u0e32\u0e07\u0e01\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e17\u0e35\u0e48\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e2b\u0e25\u0e32\u0e22\u0e09\u0e1a\u0e31\u0e1a\u0e02\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49","og_url":"https:\/\/entechsi.com\/en\/%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%ad%e0%b8%b2%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%82%e0%b8%99%e0%b8%b2%e0%b8%94%e0%b8%a2%e0%b9%88%e0%b8%ad%e0%b8%a1-microclim\/","og_site_name":"ENTECH SI CO., LTD.","article_published_time":"2024-08-15T01:38:45+00:00","article_modified_time":"2024-08-15T03:15:11+00:00","og_image":[{"width":468,"height":308,"url":"https:\/\/entechsi.com\/wp-content\/uploads\/2024\/08\/\u0e2a\u0e20\u0e32\u0e1e\u0e20\u0e39\u0e21\u0e34\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e02\u0e19\u0e32\u0e14\u0e22\u0e48\u0e2d\u0e21-Microclimate-\u0e01\u0e31\u0e1a\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22-banner.jpg","type":"image\/jpeg"}],"author":"entech_admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"entech_admin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/entechsi.com\/en\/%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%ad%e0%b8%b2%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%82%e0%b8%99%e0%b8%b2%e0%b8%94%e0%b8%a2%e0%b9%88%e0%b8%ad%e0%b8%a1-microclim\/#article","isPartOf":{"@id":"https:\/\/entechsi.com\/en\/%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%ad%e0%b8%b2%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%82%e0%b8%99%e0%b8%b2%e0%b8%94%e0%b8%a2%e0%b9%88%e0%b8%ad%e0%b8%a1-microclim\/"},"author":{"name":"entech_admin","@id":"https:\/\/entechsi.com\/en\/th\/#\/schema\/person\/00bd16e1c5f992fbba3a8654f2bf4557"},"headline":"\u0e2a\u0e20\u0e32\u0e1e\u0e20\u0e39\u0e21\u0e34\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e02\u0e19\u0e32\u0e14\u0e22\u0e48\u0e2d\u0e21 (Microclimate) \u0e01\u0e31\u0e1a\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22","datePublished":"2024-08-15T01:38:45+00:00","dateModified":"2024-08-15T03:15:11+00:00","mainEntityOfPage":{"@id":"https:\/\/entechsi.com\/en\/%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%ad%e0%b8%b2%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%82%e0%b8%99%e0%b8%b2%e0%b8%94%e0%b8%a2%e0%b9%88%e0%b8%ad%e0%b8%a1-microclim\/"},"wordCount":78,"commentCount":0,"publisher":{"@id":"https:\/\/entechsi.com\/en\/th\/#organization"},"image":{"@id":"https:\/\/entechsi.com\/en\/%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%ad%e0%b8%b2%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%82%e0%b8%99%e0%b8%b2%e0%b8%94%e0%b8%a2%e0%b9%88%e0%b8%ad%e0%b8%a1-microclim\/#primaryimage"},"thumbnailUrl":"https:\/\/entechsi.com\/wp-content\/uploads\/2024\/08\/\u0e2a\u0e20\u0e32\u0e1e\u0e20\u0e39\u0e21\u0e34\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e02\u0e19\u0e32\u0e14\u0e22\u0e48\u0e2d\u0e21-Microclimate-\u0e01\u0e31\u0e1a\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22-banner.jpg","keywords":["Microclimate","WBGT","Wet Bulb Globe Temperature","\u0e2a\u0e20\u0e32\u0e1e\u0e20\u0e39\u0e21\u0e34\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e02\u0e19\u0e32\u0e14\u0e22\u0e48\u0e2d\u0e21"],"articleSection":["Blog"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/entechsi.com\/en\/%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%ad%e0%b8%b2%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%82%e0%b8%99%e0%b8%b2%e0%b8%94%e0%b8%a2%e0%b9%88%e0%b8%ad%e0%b8%a1-microclim\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/entechsi.com\/en\/%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%ad%e0%b8%b2%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%82%e0%b8%99%e0%b8%b2%e0%b8%94%e0%b8%a2%e0%b9%88%e0%b8%ad%e0%b8%a1-microclim\/","url":"https:\/\/entechsi.com\/en\/%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%ad%e0%b8%b2%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%82%e0%b8%99%e0%b8%b2%e0%b8%94%e0%b8%a2%e0%b9%88%e0%b8%ad%e0%b8%a1-microclim\/","name":"\u0e2a\u0e20\u0e32\u0e1e\u0e20\u0e39\u0e21\u0e34\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e02\u0e19\u0e32\u0e14\u0e22\u0e48\u0e2d\u0e21 (Microclimate) \u0e01\u0e31\u0e1a\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 - ENTECH SI CO., LTD.","isPartOf":{"@id":"https:\/\/entechsi.com\/en\/th\/#website"},"primaryImageOfPage":{"@id":"https:\/\/entechsi.com\/en\/%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%ad%e0%b8%b2%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%82%e0%b8%99%e0%b8%b2%e0%b8%94%e0%b8%a2%e0%b9%88%e0%b8%ad%e0%b8%a1-microclim\/#primaryimage"},"image":{"@id":"https:\/\/entechsi.com\/en\/%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%ad%e0%b8%b2%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%82%e0%b8%99%e0%b8%b2%e0%b8%94%e0%b8%a2%e0%b9%88%e0%b8%ad%e0%b8%a1-microclim\/#primaryimage"},"thumbnailUrl":"https:\/\/entechsi.com\/wp-content\/uploads\/2024\/08\/\u0e2a\u0e20\u0e32\u0e1e\u0e20\u0e39\u0e21\u0e34\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e02\u0e19\u0e32\u0e14\u0e22\u0e48\u0e2d\u0e21-Microclimate-\u0e01\u0e31\u0e1a\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22-banner.jpg","datePublished":"2024-08-15T01:38:45+00:00","dateModified":"2024-08-15T03:15:11+00:00","description":"\u0e40\u0e14\u0e34\u0e21\u0e17\u0e35\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e2a\u0e20\u0e32\u0e1e\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e17\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e21\u0e38\u0e48\u0e07\u0e40\u0e19\u0e49\u0e19\u0e44\u0e1b\u0e17\u0e35\u0e48\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e02\u0e2d\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e14\u0e31\u0e07\u0e19\u0e31\u0e49\u0e19 \u0e2a\u0e20\u0e32\u0e1e\u0e20\u0e39\u0e21\u0e34\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e02\u0e19\u0e32\u0e14\u0e22\u0e48\u0e2d\u0e21 (Microclimate) \u0e08\u0e36\u0e07\u0e16\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e43\u0e19\u0e1b\u0e31\u0e08\u0e08\u0e31\u0e22\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07\u0e17\u0e32\u0e07\u0e01\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e17\u0e35\u0e48\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e2b\u0e25\u0e32\u0e22\u0e09\u0e1a\u0e31\u0e1a\u0e02\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49","breadcrumb":{"@id":"https:\/\/entechsi.com\/en\/%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%ad%e0%b8%b2%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%82%e0%b8%99%e0%b8%b2%e0%b8%94%e0%b8%a2%e0%b9%88%e0%b8%ad%e0%b8%a1-microclim\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/entechsi.com\/en\/%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%ad%e0%b8%b2%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%82%e0%b8%99%e0%b8%b2%e0%b8%94%e0%b8%a2%e0%b9%88%e0%b8%ad%e0%b8%a1-microclim\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/entechsi.com\/en\/%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%ad%e0%b8%b2%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%82%e0%b8%99%e0%b8%b2%e0%b8%94%e0%b8%a2%e0%b9%88%e0%b8%ad%e0%b8%a1-microclim\/#primaryimage","url":"https:\/\/entechsi.com\/wp-content\/uploads\/2024\/08\/\u0e2a\u0e20\u0e32\u0e1e\u0e20\u0e39\u0e21\u0e34\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e02\u0e19\u0e32\u0e14\u0e22\u0e48\u0e2d\u0e21-Microclimate-\u0e01\u0e31\u0e1a\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22-banner.jpg","contentUrl":"https:\/\/entechsi.com\/wp-content\/uploads\/2024\/08\/\u0e2a\u0e20\u0e32\u0e1e\u0e20\u0e39\u0e21\u0e34\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e02\u0e19\u0e32\u0e14\u0e22\u0e48\u0e2d\u0e21-Microclimate-\u0e01\u0e31\u0e1a\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22-banner.jpg","width":468,"height":308,"caption":"\u0e2a\u0e20\u0e32\u0e1e\u0e20\u0e39\u0e21\u0e34\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e02\u0e19\u0e32\u0e14\u0e22\u0e48\u0e2d\u0e21 (microclimate) \u0e01\u0e31\u0e1a\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 Banner"},{"@type":"BreadcrumbList","@id":"https:\/\/entechsi.com\/en\/%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%ad%e0%b8%b2%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%82%e0%b8%99%e0%b8%b2%e0%b8%94%e0%b8%a2%e0%b9%88%e0%b8%ad%e0%b8%a1-microclim\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/entechsi.com\/en\/"},{"@type":"ListItem","position":2,"name":"\u0e2a\u0e20\u0e32\u0e1e\u0e20\u0e39\u0e21\u0e34\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e02\u0e19\u0e32\u0e14\u0e22\u0e48\u0e2d\u0e21 (Microclimate) \u0e01\u0e31\u0e1a\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22"}]},{"@type":"WebSite","@id":"https:\/\/entechsi.com\/en\/th\/#website","url":"https:\/\/entechsi.com\/en\/th\/","name":"ENTECH SI CO., LTD.","description":"","publisher":{"@id":"https:\/\/entechsi.com\/en\/th\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/entechsi.com\/en\/th\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/entechsi.com\/en\/th\/#organization","name":"ENTECH SI CO., LTD.","url":"https:\/\/entechsi.com\/en\/th\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/entechsi.com\/en\/th\/#\/schema\/logo\/image\/","url":"https:\/\/entechsi.com\/wp-content\/uploads\/2022\/05\/logo.png","contentUrl":"https:\/\/entechsi.com\/wp-content\/uploads\/2022\/05\/logo.png","width":289,"height":30,"caption":"ENTECH SI CO., LTD."},"image":{"@id":"https:\/\/entechsi.com\/en\/th\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/entechsi.com\/en\/th\/#\/schema\/person\/00bd16e1c5f992fbba3a8654f2bf4557","name":"entech_admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"\/\/www.gravatar.com\/avatar\/682736f2f76be8408aafea754aea7735?s=96&#038;r=g&#038;d=mm","url":"\/\/www.gravatar.com\/avatar\/682736f2f76be8408aafea754aea7735?s=96&#038;r=g&#038;d=mm","contentUrl":"\/\/www.gravatar.com\/avatar\/682736f2f76be8408aafea754aea7735?s=96&#038;r=g&#038;d=mm","caption":"entech_admin"},"url":"https:\/\/entechsi.com\/en\/author\/entech_admin\/"}]}},"_links":{"self":[{"href":"https:\/\/entechsi.com\/en\/wp-json\/wp\/v2\/posts\/11221","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/entechsi.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/entechsi.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/entechsi.com\/en\/wp-json\/wp\/v2\/users\/150"}],"replies":[{"embeddable":true,"href":"https:\/\/entechsi.com\/en\/wp-json\/wp\/v2\/comments?post=11221"}],"version-history":[{"count":28,"href":"https:\/\/entechsi.com\/en\/wp-json\/wp\/v2\/posts\/11221\/revisions"}],"predecessor-version":[{"id":11266,"href":"https:\/\/entechsi.com\/en\/wp-json\/wp\/v2\/posts\/11221\/revisions\/11266"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/entechsi.com\/en\/wp-json\/wp\/v2\/media\/11222"}],"wp:attachment":[{"href":"https:\/\/entechsi.com\/en\/wp-json\/wp\/v2\/media?parent=11221"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/entechsi.com\/en\/wp-json\/wp\/v2\/categories?post=11221"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/entechsi.com\/en\/wp-json\/wp\/v2\/tags?post=11221"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}